{"id":34,"date":"2022-07-11T15:45:27","date_gmt":"2022-07-11T13:45:27","guid":{"rendered":"https:\/\/www.final-escape.com\/flensburg\/datenschutz\/"},"modified":"2023-02-13T10:11:13","modified_gmt":"2023-02-13T09:11:13","slug":"datenschutz","status":"publish","type":"page","link":"https:\/\/www.final-escape.com\/flensburg\/datenschutz\/","title":{"rendered":"Datenschutz"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"34\" class=\"elementor elementor-34\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6ff1caa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6ff1caa\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f57b8ae\" data-id=\"f57b8ae\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-03721f7 elementor-widget elementor-widget-heading\" data-id=\"03721f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Datenschutzerkl\u00e4rung<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0ad60d6 elementor-widget elementor-widget-text-editor\" data-id=\"0ad60d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>1. Allgemeines<\/h3>\nWir nehmen den Schutz Ihrer pers\u00f6nlichen Daten sehr ernst. Daten werden von uns gem\u00e4\u00df den geltenden gesetzlichen Datenschutzbestimmungen, ab dem 25.05.2018 insbesondere nach der europ\u00e4ischen Datenschutzgrundverordnung (im Folgenden: DSGVO genannt) sowie den landesspezifischen Datenschutzbestimmungen \u201everarbeitet\u201c. \u201eVerarbeitung\u201c ist jeder mit oder ohne Hilfe automatisierter Verfahren ausgef\u00fchrter Vorgang oder jede solche Vorgangsreihe im Zusammenhang mit personenbezogenen Daten wie das Erheben, das Erfassen, die Organisation, das Ordnen, die Speicherung, die Anpassung oder Ver\u00e4nderung, das Auslesen, das Abfragen, die Verwendung, die Offenlegung durch \u00dcbermittlung, Verbreitung oder eine andere Form der Bereitstellung, den Abgleich oder die Verkn\u00fcpfung, die Einschr\u00e4nkung, das L\u00f6schen oder die Vernichtung;\n\n\u201ePersonenbezogene Daten\u201c sind alle Informationen, die sich auf eine identifizierte oder identifizierbare nat\u00fcrliche Person beziehen; als identifizierbar wird eine nat\u00fcrliche Person angesehen, die direkt oder indirekt, insbesondere mittels Zuordnung zu einer Kennung wie einem Namen, zu einer Kennnummer, zu Standortdaten, zu einer Online-Kennung oder zu einem oder mehreren besonderen Merkmalen identifiziert werden kann, die Ausdruck der physischen, physiologischen, genetischen, psychischen, wirtschaftlichen, kulturellen oder sozialen Identit\u00e4t dieser nat\u00fcrlichen Person sind.\n\nNachfolgend informieren wir Sie \u00fcber die Verarbeitung Ihrer Daten, insbesondere \u00fcber die Art, den Umfang und die Zwecke der Erhebung und Verwendung Ihrer personenbezogenen Daten bei Ihrem Besuch unseres Internetauftritts und Nutzung unserer Angebote und Dienste sowie der entsprechenden Rechtsgrundlagen der einzelnen Verarbeitungsvorg\u00e4nge. Dar\u00fcber hinaus erl\u00e4utern wir Ihnen im Rahmen unserer Datenschutzerkl\u00e4rung welche Rechte Ihnen hinsichtlich der Datenverarbeitung zustehen.<br><br>\n\n<h3>2. Verantwortliche Stelle f\u00fcr die Datenverarbeitung<\/h3>\nWir sind als Anbieter unserer Internetdienste die f\u00fcr die Datenverarbeitung verantwortliche Stelle. Sie erreichen uns unter nachfolgend angegebenen Kontaktdaten:<br><br>\n\nFinal Escape 2.1 GmbH<br>\nPrenzlauer Allee 23<br>\nDE-10405 Berlin<br><br>\n\nTelefon:\u00a0<a href=\"tel:03091441886\">+49 (0)30 \u2013 91441886<\/a><br>\nE-Mail:\u00a0<a href=\"mailto:berlin@final-escape.de\">berlin@final-escape.de<\/a><br><br>\n\n<h3>3. Verarbeitung Ihrer Daten<\/h3>\nArt, Umfang und Zwecke der Verarbeitung Ihrer Daten unterscheiden sich danach, ob Sie unseren Internetauftritt nur besuchen oder von uns angebotene Dienste und\/oder Leistungen in Anspruch nehmen:<br><br>\n<h3>a) Besuch unserer Internetseiten (Server-Logfiles)<\/h3>\nBei einem Besuch unserer Internetseite speichert der Server in sogenannten Server-Logfiles Daten, die Ihr Internetbrowser automatisch an den Server \u00fcbermittelt, insbesondere:<br><br>\n\n\u2022 Datum und Uhrzeit des Abrufs einer unserer Internetseiten<br>\n\u2022 Ihren Browsertyp und die jeweilige Version des Browsers<br>\n\u2022 das verwendete Betriebssystem<br>\n\u2022 die von Ihnen zuletzt besuchte Seite (sogenannte Referrer URL)<br>\n\u2022 die \u00fcbertragene Datenmenge und der Zugriffsstatus (Datei \u00fcbertragen, Datei nicht gefunden etc.) sowie<br>\n\u2022 Ihre IP-Adresse und den anfragenden Provider.<br><br>\n\nDie Verarbeitung dieser Daten erfolgt, um die Nutzung der von Ihnen abgerufenen Internetseiten \u00fcberhaupt zu erm\u00f6glichen, zu statistischen Zwecken, zur Verbesserung unseres Internetangebots und zur Sicherheit vor rechtswidrigen Cyberangriffen sowie um Rechtsanspr\u00fcche auszu\u00fcben, geltend zu machen oder abzuwehren. Ihre IP-Adresse wird nur so lange gespeichert, wie es notwendig ist, um m\u00f6gliche Cyberangriffe zu verteidigen und den Strafverfolgungsbeh\u00f6rden die zur Strafverfolgung notwendigen Informationen bereitzustellen.<br><br>\n\nDie vorstehend angegebenen Daten werden getrennt von s\u00e4mtlichen personenbezogenen Daten, welche Sie uns bei einem Besuch unserer Internetseiten und\/oder der Inanspruchnahme einer Leistung bzw. Dienstes mitteilen, verarbeitet und keinesfalls zusammengef\u00fchrt.<br><br>\n\nDiese vorstehend beschriebene Datenverarbeitung hat ab dem 25.05.2018 ihre Rechtsgrundlage in Artikel 6 Absatz 1 Buchstabe b) DSGVO zur Durchf\u00fchrung erforderlicher vorvertraglicher Ma\u00dfnahmen, um Ihnen die Nutzung der von Ihnen abgerufenen Internetseiten zu erm\u00f6glichen. Soweit die vorstehenden Daten zur Sicherheit vor rechtswidrigen Cyberangriffen, oder um Rechtsanspr\u00fcche auszu\u00fcben, geltend zu machen oder abzuwehren, verarbeitet werden, erfolgt dies ab dem 25.05.2018 auf der Rechtsgrundlage von Art. 6 Absatz 1 Buchstabe f) der DSGVO. Unser berechtigtes Interesse f\u00fcr diese Datenverarbeitung liegt in der Auswertung der Daten zur Verbesserung unseres Internetangebots, um gegebenenfalls Rechtsanspr\u00fcche auszu\u00fcben, geltend zu machen oder abzuwehren und darin, unsere Systeme vor rechtswidrigen Cyberangriffen zu sch\u00fctzen.<br><br>\n\n\n<h3>b) Verarbeitung von personenbezogenen Daten bei der Nutzung der von uns angebotene Dienste und\/oder Leistungen:<\/h3>\nPersonenbezogene Daten werden von uns nur dann verarbeitet, wenn dies gesetzlich erlaubt ist oder sofern Sie in die Datenverarbeitung Ihrer personenbezogenen Daten einwilligen.<br><br>\n\nSoweit Sie von uns auf unserem Internetauftritt angebotenen Dienste und Leistungen in Anspruch nehmen wollen, ist es gegebenenfalls n\u00f6tig, dass Sie dazu weitere personenbezogene Daten \u00fcbermitteln. Die zwingend von uns ben\u00f6tigten Daten sind aus den Kontakt- bzw. Buchungsformularen ersichtlich. Weitere Angaben, welche nicht zu den vorstehend beschriebenen Zwecken zwingend ben\u00f6tigt werden, k\u00f6nnen Sie freiwillig t\u00e4tigen; sie sind von uns bei der Erhebung der Daten im Rahmen des Registrierungs- bzw. Bestellprozesses entsprechend markiert.<br><br>\n\nWir verarbeiten Ihre personenbezogenen Daten f\u00fcr die vorstehenden Zwecke ab dem 25.05.2018 auf der Rechtsgrundlage von Artikel 6 Absatz 1 Buchstabe b) DSGVO um einen Vertrag mit Ihnen zu erf\u00fcllen oder zur Durchf\u00fchrung erforderlicher vorvertraglicher Ma\u00dfnahmen, welche auf Ihrer Anfrage erfolgen. Der Zweck der Verarbeitung Ihrer personenbezogenen Daten besteht demnach etwa darin, Anfragen zu bearbeiten oder die gew\u00fcnschte Dienstleistung zu erbringen zu. Ohne die Angabe der personenbezogenen Daten k\u00f6nnen wir Ihre Anfrage nicht bearbeiten und\/oder den Vertrag mit Ihnen nicht abschlie\u00dfen und die angebotene Dienste und Leistungen nicht erbringen.<br><br>\n\nDar\u00fcber hinaus verarbeiten wir Ihre Daten zu dem Zweck, um gegebenenfalls Rechtsanspr\u00fcche aus dem Vertragsverh\u00e4ltnis auszu\u00fcben, geltend zu machen oder abwehren zu k\u00f6nnen und gegebenenfalls den Strafverfolgungsbeh\u00f6rden eine Strafverfolgung bei einem Missbrauch unserer Dienste zu erm\u00f6glichen. Die vorstehende Datenverarbeitung erfolgt ab dem 25.05.2018 auf der Rechtsgrundlage von Art. 6 Absatz 1 Buchstabe f) DSGVO. Unser berechtigtes Interesse f\u00fcr eine Datenverarbeitung auf der Rechtsgrundlage von Art. 6 Absatz 1 Buchstabe f) DSGVO liegt darin, gegebenenfalls Rechtsanspr\u00fcche aus dem Vertragsverh\u00e4ltnis aus\u00fcben, geltend zu machen oder abwehren zu k\u00f6nnen und gegebenenfalls den Strafverfolgungsbeh\u00f6rden eine Strafverfolgung zu erm\u00f6glichen.<br><br>\n\nWir verarbeiten Ihre personenbezogenen Daten zudem zu dem Zweck um unseren gesetzlichen Aufbewahrungspflichten nachzukommen. Die Rechtsgrundlage f\u00fcr die Erf\u00fcllung unserer gesetzlichen Aufbewahrungspflichten ist ab dem 25.05.2018 in Artikel 6 Absatz 1 Buchstabe c) DSGVO normiert.<br><br>\n\nIhre Daten werden zur Vertragserf\u00fcllung oder zur Durchf\u00fchrung erforderlicher vorvertraglicher Ma\u00dfnahmen, welche auf Ihrer Anfrage erfolgen, ggf. an uns unterst\u00fctzende Dienstleister weitergegeben, die wir selbstverst\u00e4ndlich sorgf\u00e4ltig ausgew\u00e4hlt haben. Dabei kann es sich um technische Dienstleister oder uns beim Versand bzw. der Zahlungsabwicklung oder der Buchhaltung unterst\u00fctzende Dienstleister handeln. Die Weitergabe Ihrer personenbezogenen Daten in den vorstehend beschriebenen F\u00e4llen erfolgt ab dem 25.05.2018 entweder auf der Rechtsgrundlage von Artikel 6 Absatz 1 b) DSGVO zur Erf\u00fcllung eines Vertrags mit Ihnen oder zur Durchf\u00fchrung vorvertraglicher Ma\u00dfnahmen, welche auf Ihre Anfrage hin erfolgen oder auf einem ordnungsgem\u00e4\u00dfen Vertrag \u00fcber die Verarbeitung im Auftrag, welcher die Voraussetzungen des Artikel 28 DSGVO erf\u00fcllt.<br><br>\n\nEine Weitergabe Ihrer personenbezogenen Daten kann auch \u00fcber Tools (Programme) von Drittanbietern erfolgen, welche wir auf unserer Webseite einsetzen. Sofern Sie unseren Internetseiten aufrufen und nutzen, wird gegebenenfalls Ihre IP-Adresse und weitere Daten an die Server Drittanbieter weitergeleitet, damit die von Ihnen abgerufenen Inhalte von dem Drittanbieter an Ihren Browser gesendet werden k\u00f6nnen. Die Verarbeitung Ihrer Daten durch den Anbieter der Drittinhalte unterliegt deren Datenschutzbestimmungen. \u00dcber den Einsatz, die Funktionsweise sowie \u00fcber weitere Einzelheiten der jeweiligen Tools von Drittanbietern, welche wir auf unserer Internetseite einsetzen, informieren wir Sie im Rahmen dieser Datenschutzerkl\u00e4rung.<br><br>\n\nEine Weitergabe Ihrer personenbezogenen Daten an andere Dritte erfolgt ansonsten nur, wenn wir gesetzlich dazu verpflichtet sind (z.B. an Beh\u00f6rden um Cyberangriffe und gegebenenfalls begangene Straftaten aufzukl\u00e4ren oder an Finanz\u00e4mter um steuerlichen Pflichten nachzukommen oder an Gerichte im Falle von Rechtsstreitigkeiten) ab dem 25.05.2018 auf der Rechtsgrundlage von Artikel 6 Absatz 1 Buchstabe c) DSGVO sowie gegebenenfalls an Rechtsanw\u00e4lte und Steuerberater auf der Rechtsgrundlage von Artikel 6 Absatz 1 Buchstabe c) DSGVO bzw. Artikel 6 Absatz 1 Buchstabe f) DSGVO. Unser berechtigtes Interesse an der Weitergabe Ihrer Daten an Rechtsanw\u00e4lte liegt darin, Rechtsanspr\u00fcche auszu\u00fcben, geltend zu machen oder abzuwehren. Unser berechtigtes Interesse an der Weitergabe Ihrer Daten an externe Steuerberater liegt darin, unseren steuerlichen Verpflichtungen ordnungsgem\u00e4\u00df nachkommen zu k\u00f6nnen.<br><br>\n\n\n<h3>4. Einsatz von Cookies<\/h3>\nWir setzen auf unserer Webseite sogenannte \u201eCookies\u201c ein. Cookies sind kleine Textdateien, die im Rahmen Ihres Besuchs unserer Internetseiten von unserem Webserver an Ihren Browser gesandt und von diesem zeitlich begrenzt auf Ihrem Ger\u00e4t (z.B. PC, Smartphone, Tablet) zu unterschiedlichen Zwecken gespeichert werden. Nachfolgend informieren wir Sie \u00fcber den Einsatz von Cookies auf unserer Webseite:<br><br>\n\n<h3>a) Session-Cookies und Permanent-Cookies<\/h3>\nWir setzen auf unserer Seite Session-Cookies ein welche beim Aufruf der Homepage gesetzt werden und nur so lange g\u00fcltig sind, bis Ihr Browser wieder geschlossen wird. Dar\u00fcber hinaus setzen wir auf unserer Seite sogenannte \u201ePermanent-Cookies\u201c ein, welche sp\u00e4testens nach 12 Monaten automatisch gel\u00f6scht werden. Der Zweck der von unserer Webseite eingesetzten Session- und Permanent Cookies besteht darin, Ihnen eine effektivere Nutzung unserer Webseite zu erm\u00f6glichen und statistische Daten \u00fcber unsere Webseite zu sammeln und diese zu analysieren und zu verbessern. \u201ePermanent-Cookies\u201c erm\u00f6glichen es zudem, ein Ger\u00e4t bei einem erneuten Besuch unserer Internetseite wiederzuerkennen und Informationen zu Ihrem letzten Besuch zu speichern. Wir setzen nur dauerhafte Cookies ein, welche sp\u00e4testens nach 12 Monaten automatisch gel\u00f6scht werden. Benutzerprofile werden durch die von uns gesetzten Cookies nicht erstellt.<br><br>\n\n<h3>b) Cookies von Drittanbietern<\/h3>\nCookies k\u00f6nnen gegebenenfalls auch von Drittanbietern von Tools (Programmen), welche wir auf unserer Webseite nutzen, eingesetzt werden. Sofern wir Tools von Drittanbietern einsetzen, informieren wir Sie \u00fcber den Einsatz, die Funktionsweise sowie \u00fcber weitere Einzelheiten der jeweiligen Tools unter Punkt 15. dieser Datenschutzerkl\u00e4rung.<br><br>\n\n<h3>c) Verhinderung des Einsatzes von Cookies durch Browsereinstellungen<\/h3>\nOb Cookies gesetzt und abgerufen werden k\u00f6nnen, k\u00f6nnen Sie selber durch die Einstellungen in Ihrem Browser bestimmen. Sie k\u00f6nnen in Ihrem Browser etwa das Speichern von Cookies insgesamt deaktivieren, es auf bestimmte Webseiten beschr\u00e4nken oder Ihren Browser so konfigurieren, dass er Sie automatisch benachrichtigt, sobald ein Cookie gesetzt werden soll und Sie um Erlaubnis dazu bittet. Zudem k\u00f6nnen Sie Ihren Browser so einstellen, dass Cookies beim Schlie\u00dfen des Browser automatisch gel\u00f6scht werden. Schlie\u00dflich k\u00f6nnen Sie in Ihrem Browser gegebenenfalls eine Do-Not-Track-Funktion (\u201eDNT\u201c) aktivieren, so dass Sie automatisch nicht von einem gegebenenfalls eingesetzten Webanalyse-Tool erfasst werden. Informationen \u00fcber die Konfiguration Ihrer Browsereinstellungen k\u00f6nnen Sie der Hilfefunktion Ihres jeweiligen Internetbrowsers entnehmen.<br><br>\n\n\n<h3>5. Speicher- und L\u00f6schfristen f\u00fcr personenbezogene Daten<\/h3>\nEntf\u00e4llt der Verarbeitungszweck f\u00fcr Ihre jeweils ben\u00f6tigten personenbezogenen Daten werden Ihre von uns verarbeiteten personenbezogenen Daten routinem\u00e4\u00dfig gel\u00f6scht bzw. gesperrt, sofern Sie nicht in eine dauerhafte Speicherung Ihrer personenbezogenen Daten eingewilligt haben.<br><br>\n\nSofern einzelne Daten nach Entfall der Verarbeitungszwecke aufgrund von gesetzlichen Aufbewahrungsfristen aufbewahrt werden m\u00fcssen (z.B. steuer- und handelsrechtliche Aufbewahrungsvorschriften), tritt an die Stelle einer L\u00f6schung die Sperrung der Daten. Die aufzubewahrenden Daten d\u00fcrfen dann auf der Rechtsgrundlage des Artikels 6 Absatz 1 Buchstabe c) DSGVO ausschlie\u00dflich f\u00fcr die vorgenannten Zwecke verarbeitet werden.<br><br>\n\n<h3>6. Ihre Rechte als Betroffener der Datenverarbeitung<\/h3>\nSie haben jederzeit die nachstehend beschriebenen Rechte:<br><br>\n\n\u2022 Recht auf Best\u00e4tigung und auf Auskunft \u00fcber die bei uns verarbeiteten personenbezogenen Daten gem\u00e4\u00df Artikel 15 DSGVO<br>\n\u2022 Recht auf Berichtigung Ihrer personenbezogenen Daten gem\u00e4\u00df Artikel 16 DSGVO<br>\n\u2022 Recht auf L\u00f6schung Ihrer personenbezogenen Daten (\u201eRecht auf Vergessenwerden\u201c) gem\u00e4\u00df Artikel 17 DSGVO<br>\n\u2022 Recht auf Einschr\u00e4nkung der Verarbeitung Ihrer personenbezogenen Daten gem\u00e4\u00df Artikel 18 DSGVO<br>\n\u2022 Recht auf Daten\u00fcbertragbarkeit Ihrer personenbezogenen Daten gem\u00e4\u00df Artikel 20 DSGVO<br>\n\u2022 Sie haben gem\u00e4\u00df Artikel 22 DSGVO das Recht, nicht einer ausschlie\u00dflich auf einer automatisierten Verarbeitung \u2013 einschlie\u00dflich Profiling \u2013 beruhenden Entscheidung unterworfen zu werden, die Ihnen gegen\u00fcber rechtliche Wirkung entfaltet oder sie in \u00e4hnlicher Weise erheblich beeintr\u00e4chtigt.<br><br>\n\nBitte senden Sie uns Ihr Verlangen an die unter Ziffer 2. dieser Datenschutzerkl\u00e4rung angegebenen Kontaktdaten.<br><br>\n\n<h3>7. Widerspruchsrecht<\/h3>\nSie haben das Recht, aus Gr\u00fcnden, die sich aus ihrer besonderen Situation ergeben, jederzeit gegen die Verarbeitung Sie betreffender personenbezogener Daten, die ab dem 25.05.2018 aufgrund von Artikel 6 Absatz 1 Buchstaben e oder f DSGVO erfolgt, Widerspruch einzulegen; dies gilt auch f\u00fcr ein auf diese Bestimmungen gest\u00fctztes Profiling.<br><br>\n\nWir verarbeiten Ihre personenbezogenen Daten in diesem Fall nicht mehr, es sei denn, wir k\u00f6nnen zwingende schutzw\u00fcrdige Gr\u00fcnde f\u00fcr die Verarbeitung nachweisen, welche Ihre Interessen, Rechte und Freiheiten \u00fcberwiegen, oder die Verarbeitung der Geltendmachung, Aus\u00fcbung oder Verteidigung von Rechtsanspr\u00fcchen dient.<br><br>\n\nWerden personenbezogene Daten verarbeitet, um Direktwerbung zu betreiben, so haben Sie das Recht, jederzeit Widerspruch gegen die Verarbeitung Sie betreffender personenbezogener Daten zum Zwecke derartiger Werbung einzulegen; dies gilt auch f\u00fcr das Profiling, soweit es mit solcher Direktwerbung in Verbindung steht.<br><br>\n\nSie haben ferner das Recht, aus Gr\u00fcnden, die sich aus ihrer besonderen Situation ergeben, gegen die Sie betreffende Verarbeitung Sie betreffender personenbezogener Daten, die zu wissenschaftlichen oder historischen Forschungszwecken oder zu statistischen Zwecken gem\u00e4\u00df Artikel 89 Absatz 1 DSGVO erfolgt, Widerspruch einzulegen, es sei denn, die Verarbeitung ist zur Erf\u00fcllung einer im \u00f6ffentlichen Interesse liegenden Aufgabe erforderlich. Widersprechen Sie der Verarbeitung f\u00fcr Zwecke der Direktwerbung, so werden die personenbezogenen Daten nicht mehr f\u00fcr diese Zwecke verarbeitet.<br><br>\n\n<h3>8. Widerrufsrecht bei Einwilligungen<\/h3>\nSie k\u00f6nnen uns gegen\u00fcber ausdr\u00fccklich erteilte datenschutzrechtliche Einwilligungen jederzeit mit Wirkung f\u00fcr die Zukunft widerrufen. Die Rechtm\u00e4\u00dfigkeit der aufgrund der Einwilligung bis zum Widerruf erfolgten Verarbeitung wird durch den Widerruf nicht ber\u00fchrt.<br><br>\n\n<h3>9. Beschwerde \u00fcber Datenschutzverst\u00f6\u00dfe bei den Aufsichtsbeh\u00f6rden<\/h3>\nSofern Sie der Ansicht sind, dass Ihre Datenschutzrechte verletzt werden, k\u00f6nnen Sie sich an die Aufsichtsbeh\u00f6rde ihres Bundeslandes oder des Bundeslandes unseres Firmensitzes wenden. Betrifft eine Beschwerde ein Unternehmen, das seinen Sitz in einem anderen Bundesland hat, leitet die Aufsichtsbeh\u00f6rde die Beschwerde an die dort zust\u00e4ndige Aufsichtsbeh\u00f6rde weiter.<br><br>\n\n<h3>10. Mitteilungspflicht im Zusammenhang mit der Berichtigung oder L\u00f6schung personenbezogener Daten oder der Einschr\u00e4nkung der Verarbeitung<\/h3>\nWir teilen allen Empf\u00e4ngern, denen personenbezogene Daten offengelegt wurden, jede Berichtigung oder L\u00f6schung der personenbezogenen Daten oder eine Einschr\u00e4nkung der Verarbeitung nach Artikel 16, Artikel 17 Absatz 1 und Artikel 18 DSGVO mit, es sei denn, dies erweist sich als unm\u00f6glich oder ist mit einem unverh\u00e4ltnism\u00e4\u00dfigen Aufwand verbunden. Wir unterrichten Sie auch \u00fcber diese Empf\u00e4nger, wenn Sie dies verlangen.<br><br>\n\n<h3>11. Gesetzliche oder vertragliche Vorschriften zur Bereitstellung Ihrer personenbezogenen Daten sowie Informationen \u00fcber die Erforderlichkeit f\u00fcr den Vertragsabschluss sowie \u00fcber Ihre Verpflichtung, die personenbezogenen Daten bereitzustellen und m\u00f6gliche Folgen der Nichtbereitstellung:<\/h3>\n\nWie zuvor bereits beschrieben, erheben und verarbeiten wir Ihre personenbezogenen Daten insbesondere f\u00fcr die Erf\u00fcllung eines Vertrags mit Ihnen oder zur Durchf\u00fchrung vorvertraglicher Ma\u00dfnahmen, die auf Ihre Anfrage erfolgen. Zum Teil ist die Angabe von personenbezogenen Daten bei Vertragsabschl\u00fcssen (z.B. f\u00fcr Rechnungen) aufgrund von steuer- und\/oder handelsrechtlichen Vorschriften gesetzlich vorgeschrieben, ansonsten handelt es sich um eine vertragliche bzw. vorvertragliche Verpflichtung. Sofern Sie uns keine personenbezogenen Daten mitteilen, hat dies zur Folge, dass wir keinen Vertrag mit Ihnen abschlie\u00dfen k\u00f6nnen und\/oder Ihre Anfragen nicht beantworten k\u00f6nnen.<br><br>\nSoweit wir Ihre personenbezogenen Daten auf der Grundlage eines berechtigten Interesses gem\u00e4\u00df Art. 6 Absatz 1 Buchstabe f) der DSGVO verarbeiten, ist die Bereitstellung Ihrer Daten zu diesen Zwecken weder vertraglich noch gesetzlich vorgeschrieben. Die Einzelheiten der Datenverarbeitung auf der Grundlage eines berechtigten Interesses k\u00f6nnen Sie den Informationen in dieser Datenschutzerkl\u00e4rung an den jeweiligen Stellen entnehmen. Sofern Sie uns keine personenbezogenen Daten zu diesen Zwecken bereitstellen, kann dies zur Folge haben, dass Sie unsere Webseite und Leistungen nicht bzw. nicht in vollem Umfang nutzen k\u00f6nnen.<br><br>\n<h3>12. Automatisierte Entscheidungen im Einzelfall einschlie\u00dflich Profiling<\/h3>\nWir setzen keine automatisierten Entscheidungsfindungen \u2013 einschlie\u00dflich Profiling gem\u00e4\u00df Artikel 22 Abs\u00e4tze 1 und 4 der DSGVO \u2013 ein.<br><br>\n<h3>13. Datensicherheit<\/h3>\nWir setzen technische und organisatorische Sicherheitsma\u00dfnahmen ein, um die Verarbeitung von personenbezogenen Daten zu sch\u00fctzen, insb. gegen zuf\u00e4llige oder vors\u00e4tzliche Manipulation, Verlust, Zerst\u00f6rung oder gegen den Angriff unberechtigter Personen. Unsere Sicherheitsma\u00dfnahmen werden entsprechend der technologischen Entwicklung fortlaufend verbessert.<br><br>\n\n<h3>14. Fragen \/ Anmerkungen<\/h3>\nFragen oder Anmerkungen zu dieser Datenschutzerkl\u00e4rung oder allgemein zum Datenschutz k\u00f6nnen Sie gerne an unsere Kontaktdaten, welche Sie Ziffer 2. dieser Datenschutzerkl\u00e4rung entnehmen k\u00f6nnen, richten.<br><br>\n<h3>15. Einsatz von Tools und Inhalte von Drittanbietern<\/h3>\nWir setzen derzeit Tools von folgenden Drittanbietern ein:<br><br>\n<h3>Google-Analytics<\/h3>\nUns ist es wichtig, unsere Internetseiten m\u00f6glichst optimal auszugestalten und damit f\u00fcr unsere Besucher attraktiv zu machen. Dazu ist es n\u00f6tig, dass wir wissen, welche Teile unserer Internetseite bei unseren Besuchern ankommen.<br><br>\n\nZu diesem Zweck setzen wir auf unserer Internetseite den Webanalysedienst Google Analytics, einen Webanalysedienst der Google Inc. (\u201eGoogle\u201c), ein. Google Analytics verwendet sog. \u201eCookies\u201c, Textdateien, die auf Ihrem Computer gespeichert werden und die eine Analyse der Benutzung der Website durch Sie erm\u00f6glichen. Die durch den Cookie erzeugten Informationen \u00fcber Ihre Benutzung dieser Website werden in der Regel an einen Server von Google in den USA \u00fcbertragen und dort gespeichert.<br><br>\n\nWir verwenden Google Analytics auf dieser Website unter Aktivierung der IP-Anonymisierung, d.h. Ihre IP-Adresse wird von Google innerhalb von Mitgliedstaaten der Europ\u00e4ischen Union oder in anderen Vertragsstaaten des Abkommens \u00fcber den Europ\u00e4ischen Wirtschaftsraum zuvor gek\u00fcrzt. Nur in Ausnahmef\u00e4llen wird die volle IP-Adresse an einen Server von Google in den USA \u00fcbertragen und dort gek\u00fcrzt. Im Auftrag des Betreibers dieser Website wird Google diese Informationen benutzen, um Ihre Nutzung der Website auszuwerten, um Reports \u00fcber die Websiteaktivit\u00e4ten zusammenzustellen und um weitere mit der Websitenutzung und der Internetnutzung verbundene Dienstleistungen gegen\u00fcber dem Websitebetreiber zu erbringen. Die im Rahmen von Google Analytics von Ihrem Browser \u00fcbermittelte IP-Adresse wird nicht mit anderen Daten von Google zusammengef\u00fchrt.<br><br>\n\nSie k\u00f6nnen die Speicherung der Cookies durch eine entsprechende Einstellung Ihrer Browser-Software verhindern. Informationen \u00fcber die Konfiguration Ihrer Browsereinstellungen k\u00f6nnen Sie der Hilfefunktion Ihres jeweiligen Internetbrowsers entnehmen. Wir weisen Sie jedoch darauf hin, dass Sie in diesem Fall gegebenenfalls nicht s\u00e4mtliche Funktionen dieser Website vollumf\u00e4nglich werden nutzen k\u00f6nnen.<br><br>\n\nDar\u00fcber hinaus k\u00f6nnen Sie die Erfassung der Daten durch ein Browser-Plugin verhindern. Dieses Plugin setzt ein Opt-Out-Cookie und verhindert so die zuk\u00fcnftige Erfassung und Verarbeitung Ihrer Daten durch Google Analytics. Ein Browser-Plugin k\u00f6nnen Sie unter dem Link\u00a0<a href=\"http:\/\/tools.google.com\/dlpage\/gaoptout?hl=de\" target=\"_blank\" rel=\"noopener noreferrer\">http:\/\/tools.google.com\/dlpage\/gaoptout?hl=de<\/a>\u00a0herunterladen und installieren.<br><br>\n\nSie k\u00f6nnen die Erfassung durch Google Analytics auch verhindern, indem Sie auf folgenden Link zum \u201eDeaktivieren von Google Analytics\u201c [Link zum Aktivieren des Opt-Out-Cookies] klicken. Es wird ein Opt-Out-Cookie gesetzt, das die zuk\u00fcnftige Erfassung Ihrer Daten beim Besuch dieser Website verhindert:<br><br>\n\nWeitere Informationen \u00fcber Nutzungsbedingungen und Datenschutz von Google finden Sie unter\u00a0<a href=\"http:\/\/www.google.com\/analytics\/terms\/de.html\" target=\"_blank\" rel=\"noopener noreferrer\">http:\/\/www.google.com\/analytics\/terms\/de.html<\/a>\u00a0bzw.unter\u00a0<a href=\"http:\/\/www.google.de\/intl\/de\/policies\/terms\/regional.html\" target=\"_blank\" rel=\"noopener noreferrer\">http:\/\/www.google.de\/intl\/de\/policies\/terms\/regional.html<\/a>.<br><br>\n\nDer vorstehend beschriebene Einsatz von Google-Analytics erfolgt ab dem 25.05.2018 auf Grundlage von Art. 6 Abs. 1 Buchstabe f) DSGVO. Unser berechtigtes Interesse an der Analyse des Nutzerverhaltens ist eine Optimierung unseres Webangebotes und die optimale Vermarktung unserer Leistungen.<br><br>\n<h3>YouTube-Videos<\/h3>\nWir binden auf unserer Webseite Videos des Dienstes \u201eYouTube\u201c, einem Dienst der Firma YouTube LLC 901 Cherry Ave, San Bruno, CA 94066, USA im erweiterten Datenschutzmodus ein.<br><br>\n\nYouTube-Videos werden nicht auf unserem eigenen Server gespeichert, sondern auf Servern von YouTube. Nach den eigenen Angaben von Youtube werden bei der Einbettung eines YouTube-Videos keine Informationen von YouTube \u00fcber die Besucher auf einer Website gespeichert, es sei denn, ein Besucher sieht sich das eingebettete Video an. In diesem Fall setzt YouTube Cookies zur Erfassung von Videostatistiken, zur Vermeidung von Betrug und zur Verbesserung der Userfreundlichkeit und speichert Ihre IP-Adresse. Auch wird beim Ansehen eines Videos Kontakt mit Googles Werbenetzwerk \u201eDoubleClick\u201c aufgenommen. Sobald ein eingebettetes You-Tube-Video gestartet wird, haben wir demnach keinen Einfluss mehr auf diese Datenverarbeitung durch YouTube. Weitere Informationen \u00fcber Datenschutz bei YouTube finden Sie in deren Datenschutzerkl\u00e4rung unter:<br><br>\n\n<a href=\"http:\/\/www.youtube.com\/t\/privacy_at_youtube\" target=\"_blank\" rel=\"noopener noreferrer\">http:\/\/www.youtube.com\/t\/privacy_at_youtube<\/a><br><br>\n\nDer vorstehend beschriebene Einsatz von YouTube erfolgt ab dem 25.05.2018 auf Grundlage von Art. 6 Abs. 1 Buchstabe f) DSGVO. Unser berechtigtes Interesse an der Einbindung von YouTube-Videos ist die Optimierung unserer Webseite und die Vermarktung unserer Leistungen.<br><br>\n<h3>Facebook \u201eCustom Audiences\u201c<\/h3>\nDiese Website verwendet die Remarketing-Funktion \u201eCustom Audiences\u201c der Facebook Inc. (\u201eFacebook\u201c). Diese Funktion dient uns dazu, statistische Daten \u00fcber unsere Facebook-Werbeanzeigen nachzuverfolgen und zu analysieren, um so unsere zuk\u00fcnftigen Werbema\u00dfnahmen zu optimieren. Die erhobenen Daten sind f\u00fcr uns als Betreiber dieser Website anonym, wir k\u00f6nnen keine R\u00fcckschl\u00fcsse auf die Identit\u00e4t der Nutzer ziehen.<br><br>\n\nDer Facebook-Z\u00e4hlpixel benutzt zur einmaligen Identifizierung des Benutzers und des Browsers ein Cookie, das 3 Monate gespeichert wird.<br><br>\n\nDie Daten werden auch von Facebook gespeichert und verarbeitet, sodass eine Verbindung zum jeweiligen Nutzerprofil bei Facebook m\u00f6glich ist und Facebook die Daten f\u00fcr eigene Werbezwecke, insbesondere f\u00fcr interessenbezogene Werbeanzeigen (\u201eFacebook-Ads\u201c), verwenden kann. Auf diese Datenverarbeitung durch Facebook haben wir keinen Einfluss.<br><br>\n\nWeitere Informationen \u00fcber den Einsatz von Cookies und Custom Audiences durch Facebook finden Sie in deren Datenschutzerkl\u00e4rung unter:<br><br>\n\n<a href=\"https:\/\/www.facebook.com\/policies\/cookies\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.facebook.com\/policies\/cookies\/<\/a><br><br>\n\n<a href=\"https:\/\/www.facebook.com\/about\/privacy\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.facebook.com\/about\/privacy<\/a><br><br>\n\nDer vorstehend beschriebene Einsatz des Facebook Custom Audiences Technologie erfolgt ab dem 25.05.2018 aufgrund unserer berechtigten Werbeinteressen und damit auf der Rechtsgrundlage von Artikel 6 Absatz 1 Buchstabe f) DSGVO.<br><br>\n\n<h3>Instagram-Funktionen<\/h3>\nDiese Website verwendet Funktionen und Inhalte des Dienstes Instagram der Firma Instagram Inc., 1601 Willow Road, Menlo Park, CA, 94025, USA. Wir setzen die Funktionen von Instagram ein, um Inhalte wie z.B. Videos, Bilder und Texte auf unserer Webseite zu pr\u00e4sentieren und Nutzern die M\u00f6glichkeit zu geben die Inhalte zu abonnieren und an andere Nutzer zu empfehlen.<br><br>\n\nDie Instagram-Funktionen setzen Session-Cookies und kann daher den Aufruf unserer Instagram-Inhalte dem Instagram-Profil eines Nutzers gegebenenfalls zuordnen. Auf diese Datenverarbeitung durch Instagram haben wir keinen Einfluss.<br><br>\n\nInformationen \u00fcber Art, Umfang und Zweck der Erhebung und Verwendung personenbezogener Daten durch Instagram sowie Ihre diesbez\u00fcglichen Rechte und den Einstellungsm\u00f6glichkeiten zum Schutz Ihrer Privatsph\u00e4re entnehmen Sie bitte den Datenschutzhinweisen von Instagram:<br><br>\n\n<a href=\"http:\/\/instagram.com\/about\/legal\/privacy\/\" target=\"_blank\" rel=\"noopener noreferrer\">http:\/\/instagram.com\/about\/legal\/privacy\/<\/a>.<br><br>\n\nSofern Sie die zuvor genannten Daten\u00fcbermittlungen an Instagram nicht w\u00fcnschen, empfehlen wir Ihnen, vor einem Besuch unserer Webseiten JavaScript in Ihrem Browser abzuschalten und die Speicherung von Cookies zu deaktivieren und die vorhandenen Cookies aus Ihrem Browser zu l\u00f6schen. Informationen \u00fcber die Konfiguration Ihrer Browsereinstellungen k\u00f6nnen Sie der Hilfefunktion Ihres jeweiligen Internetbrowsers entnehmen.<br><br>\n\nDer vorstehend beschriebene Einsatz der Instagram-Funktionen erfolgt ab dem 25.05.2018 aufgrund unserer berechtigten gesch\u00e4ftlichen Werbeinteressen und damit auf der Rechtsgrundlage von Artikel 6 Absatz 1 Buchstabe f) DSGVO.<br><br>\n\n<h3>Facebook Plug-Ins<\/h3>\nWir setzen auf unseren Internetseiten Programme (sogenannte \u201ePlug-Ins\u201c) der Fa. Facebook Inc., 1601 S. California Ave, Palo Alto, CA 94304, USA (im Folgenden: Facebook genannt) ein. Diesbez\u00fcglich gilt folgendes:<br><br>\n\nSie erkennen diese Plug-Ins an den Logos von Facebook (wei\u00dfes \u201ef\u201c auf blauer Kachel oder ein \u201eDaumen hoch\u201c-Zeichen) und\/oder den entsprechenden Zus\u00e4tzen \u201eGef\u00e4llt mir\u201c, \u201eI Like\u201c bzw. der Bezeichnung \u201eFacebook Social Plugin\u201c.<br><br>\n\nBei einem Besuch einer unserer Webseiten auf denen ein Facebook-Plug-In eingesetzt wird, wird eine direkte Verbindung zwischen Ihrem Browser und Facebook hergestellt, sofern Sie diese Funktion \u00fcber eine entsprechende Aktivierungsfunktion auf unser Webseite aktivieren und das Social-Media-Plugin nutzen. Nach den Angaben von Facebook werden dann folgende Daten des Nutzers an Facebook \u00fcbertragen und dort gespeichert:<br><br>\n\nFacebook sieht das Datum und die Uhrzeit Ihres Besuchs, die Webseite, auf der Sie sich befinden (URL) sowie weitere technische Informationen \u00fcber die IP-Adresse, den Browser und das von Ihnen verwendete Betriebssystem. Dies sind Daten, mit denen Facebook Ihr Erlebnis optimieren kann, je nachdem welchen Browser Sie verwenden und ob Sie bei Facebook mit Ihren pers\u00f6nlichen Benutzerdaten angemeldet sind oder nicht.<br><br>\n\nSofern Sie bei einem Besuch unserer Webseiten gleichzeitig mit Ihren pers\u00f6nlichen Benutzerdaten bei Facebook angemeldet sind, wird durch den Besuch unserer Webseiten und der Aktivierung des Social-Media-Plugins zus\u00e4tzlich Ihre Nutzer-Kennnummer an Facebook \u00fcbertragen, wodurch die \u00fcbersendeten Daten Ihrem Benutzerkonto zugeordnet werden k\u00f6nnen. Nach eigenen Angaben von Facebook ist dies notwendig, um Ihnen den richtigen sozialen Kontext bzw. das richtige soziale Umfeld auf den Webseiten von Facebook anzuzeigen.<br><br>\n\nDurch die Nutzung der Facebook-Plug-Ins durch den Nutzer, z.B. dem Anklicken des \u201eGef\u00e4llt mir\u201c-Buttons stellt das Facebook-Plug-In eine direkte Verbindung zwischen Ihrem Browser und den Facebook-Servern her. Hierbei werden sodann zus\u00e4tzliche Informationen an Facebook gesendet, dort gespeichert und in Ihrem pers\u00f6nlichen Facebook-Profil ver\u00f6ffentlicht, insbesondere dass Sie unsere Webseite, auf welcher das Facebook-Plug-In genutzt wurde, aufgerufen haben und Ihnen diese Webseite gefallen hat bzw. sie einen Besuch dieser Webseite empfehlen.<br><br>\n\nSofern Sie die zuvor genannten Daten\u00fcbermittlungen an Facebook nicht w\u00fcnschen, empfehlen wir Ihnen, die Facebook Plug-Ins auf unserer Webseite nicht zu aktivieren und\/oder sich vor einem Besuch unserer Webseiten von Facebook abzumelden.<br><br>\n\nInformationen \u00fcber Art, Umfang und Zweck der Erhebung und Verwendung personenbezogener Daten durch Facebook sowie Ihre diesbez\u00fcglichen Rechte und den Einstellungsm\u00f6glichkeiten zum Schutz Ihrer Privatsph\u00e4re entnehmen Sie bitte den Datenschutzhinweisen von Facebook unter\u00a0<a href=\"http:\/\/de-de.facebook.com\/policy.php\" target=\"_blank\" rel=\"noopener noreferrer\">http:\/\/de-de.facebook.com\/policy.php<\/a>.<br><br>\n\nDer vorstehend beschriebene Einsatz der Facebook-Plugins erfolgt ab dem 25.05.2018 aufgrund unserer berechtigten gesch\u00e4ftlichen Werbeinteressen und damit auf der Rechtsgrundlage von Artikel 6 Absatz 1 Buchstabe f) DSGVO.<br><br>\n\n<h3>Google+1 Plugins<\/h3>\nWir verwenden auf unseren Webseiten den \u201e+1-Button\u201c der Google Inc., 1600 Amphitheatre Parkway, Mountain View, CA 94043, USA (nachfolgend \u201eGoogle\u201c genannt). Der Button ist mit dem Logo \u201c+1\u2033 gekennzeichnet. Mithilfe des +1-Buttons k\u00f6nnen Sie Informationen weltweit ver\u00f6ffentlichen, sofern Sie \u00fcber ein Google-Profil verf\u00fcgen.<br><br>\n\nWenn Sie eine unserer Webseiten, auf der ein +1-Button verwendet wird, besuchen und ihn \u00fcber unsere Aktivierungsfunktion auf unser Webseite aktivieren ohne den +1-Button danach anzuklicken, protokolliert Google Ihren Browserverlauf f\u00fcr ca. zwei Wochen und wertet Ihren Besuch auf dieser Webseite ausschlie\u00dflich zu Systemwartungs- und Fehlerbehebungszwecken aus. Der +1-Button wird in diesem Fall nicht dazu verwendet, Ihre Besuche im Web zu erfassen oder Ihren Besuch der Webseite in anderer Weise auszuwerten. Diese Daten werden auch nicht nach individuellen Profilen, Nutzernamen oder URLs strukturiert.<br><br>\n\nSofern Sie bei Google angemeldet sind und den +1-Button \u00fcber unsere Aktivierungsfunktion anklicken, speichert Google sowohl die Information, dass Sie f\u00fcr einen Inhalt +1 gegeben haben, als auch Informationen \u00fcber die Seite, die Sie beim Klicken auf +1 angesehen haben. Im Einzelnen werden Informationen \u00fcber Ihr Google-Profil, die von Ihnen empfohlene URL, Ihre IP-Adresse und andere Browser-bezogene Informationen gespeichert. Au\u00dferdem werden die Informationen \u00fcber Ihre +1-Aktivit\u00e4ten von Google gespeichert, um die Google-Dienste f\u00fcr Sie und andere zu verbessern.<br><br>\n\nEs wird darauf hingewiesen, dass die Vergabe von +1 ein \u00f6ffentlicher Vorgang ist. Jeder, der eine Google-Suche ausf\u00fchrt oder Inhalte im Web aufruft, denen Sie +1 geben, kann potenziell sehen, dass Sie dem betreffenden Inhalt ein +1 gegeben haben. Ihre +1-Empfehlungen k\u00f6nnen z.B. als Hinweise zusammen mit Ihrem Profilnamen und Ihrem Foto in Google-Diensten, wie etwa in Suchergebnissen oder in Ihrem Google-Profil oder an anderen Stellen auf Websites und Anzeigen im Internet eingeblendet werden. Aus den zuvor genannten Gr\u00fcnden sollten Sie +1-Empfehlungen daher nur f\u00fcr Seiten geben, wenn Sie sicher sind, dass Sie diese Empfehlung mit der ganzen Welt teilen m\u00f6chten. Weitere Informationen von Google \u00fcber die \u201e+1-Hinweise im Web\u201c finden Sie unter:<br><br>\n\n<a href=\"http:\/\/www.google.com\/support\/+\/bin\/static.py?page=guide.cs&amp;guide=1347964&amp;topic=1364508&amp;answer=1186915\" target=\"_blank\" rel=\"noopener noreferrer\">http:\/\/www.google.com\/support\/+\/bin\/static.py?page=guide.cs&amp;guide=1347964&amp;topic=1364508&amp;answer=1186915<\/a><br><br>\n\n\u00dcber die Google +1-Schaltfl\u00e4che erhalten Sie und andere Nutzer auch personalisierte Inhalte von Google und den Partnerunternehmen von Google. Weitere Informationen von Google \u00fcber die \u201e+1-Personalisierung auf Websites Dritter\u201c finden Sie hier:<br><br>\n\n<a href=\"http:\/\/www.google.com\/support\/+\/bin\/static.py?hl=de&amp;page=guide.cs&amp;guide=1347964&amp;topic=1364508&amp;answer=1152622&amp;rd=1\" target=\"_blank\" rel=\"noopener noreferrer\">http:\/\/www.google.com\/support\/+\/bin\/static.py?hl=de&amp;page=guide.cs&amp;guide=1347964&amp;topic=1364508&amp;answer=1152622&amp;rd=1<\/a>.<br><br>\n\nSofern Sie die zuvor genannten Daten\u00fcbermittlungen an Google nicht w\u00fcnschen, empfehlen wir Ihnen, das Google+1-Plugin nicht zu aktivieren und sich vor einem Besuch unserer Webseiten von Google abzumelden und\/oder die Verwendung von JavaScript in Ihrem Browser abzuschalten. Informationen \u00fcber die Konfiguration Ihrer Browsereinstellungen k\u00f6nnen Sie der Hilfefunktion Ihres jeweiligen Internetbrowsers entnehmen.<br><br>\n\nAllgemeine Informationen \u00fcber den Umgang von Google mit dem Datenschutz bei Verwendung des +1-Buttons sowie zu Ihren Profileinstellungsm\u00f6glichkeiten zum Schutz Ihrer Privatsph\u00e4re entnehmen Sie bitte den \u201eGoogle +1-Schaltfl\u00e4che \u2013 Datenschutzbestimmungen\u201c:<br><br>\n\n<a href=\"https:\/\/www.google.com\/intl\/de\/+\/policy\/+1button.html\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.google.com\/intl\/de\/+\/policy\/+1button.html<\/a><br><br>\n\nsowie den Informationen von Google zum \u201eDatenschutz bei der Nutzung der +1-Schaltfl\u00e4che\u201c unter:<br><br>\n\n<a href=\"http:\/\/www.google.com\/support\/+\/bin\/static.py?hl=de&amp;page=guide.cs&amp;guide=1347964&amp;topic=1364508&amp;answer=1319578&amp;rd=1\" target=\"_blank\" rel=\"noopener noreferrer\">http:\/\/www.google.com\/support\/+\/bin\/static.py?hl=de&amp;page=guide.cs&amp;guide=1347964&amp;topic=1364508&amp;answer=1319578&amp;rd=1<\/a>.<br><br>\n\nDer vorstehend beschriebene Einsatz der Google+1-Plugins erfolgt ab dem 25.05.2018 aufgrund unserer berechtigten gesch\u00e4ftlichen Werbeinteressen und damit auf der Rechtsgrundlage von Artikel 6 Absatz 1 Buchstabe f) DSGVO.<br><br>\n<h3>Hinweise zu Tripadvisor Plugins<\/h3>\nDiese Website verwendet das Plugin der Firma TripAdvisor LLC, 400 1st Avenue,Needham, MA 02494, USA, ein Onlineunternehmen der Reisebranche die Bewertungen und Meinungen der Nutzer \u00fcber Touristische Angebote anbietet und diese mit Buchungsempfehlungen kombiniert. Sie erkennen diese Plug-Ins an den Logos von Tripadvisor (eine stilisierte Eule). Wir setzen das Plugins von Tripadvisor ein, um Kundenrezensionen \u00fcber uns neutral darzustellen.<br><br>\n\nBei einem Besuch einer unserer Webseiten auf denen ein Tripadvisor-Plug-In eingesetzt wird, wird eine direkte Verbindung zwischen Ihrem Browser und Tripadvisor hergestellt. Nach den Angaben von Tripadvisor wird dann Ihre IP-Adresse sowie Informationen dar\u00fcber, welche unserer Seiten Sie besucht haben, \u00fcbermittelt und Cookies von Tripadvisor auf Ihrem Ger\u00e4t zu Tracking-Zwecken gesetzt. Informationen \u00fcber Art, Umfang und Zweck der Erhebung und Verwendung personenbezogener Daten durch Tripadvisor sowie Ihre diesbez\u00fcglichen Rechte und den Einstellungsm\u00f6glichkeiten zum Schutz Ihrer Privatsph\u00e4re entnehmen Sie bitte den Datenschutzhinweisen von Tripadvisor:<br><br>\n\n<a href=\"https:\/\/www.tripadvisor.de\/pages\/privacy.html\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.tripadvisor.de\/pages\/privacy.html<\/a>.<br><br>\n\nSofern Sie die zuvor genannten Daten\u00fcbermittlungen an Tripadvisor nicht w\u00fcnschen, empfehlen wir Ihnen, vor einem Besuch unserer Webseiten JavaScript in Ihrem Browser abzuschalten und die Speicherung von Cookies zu deaktivieren und die vorhandenen Cookies aus Ihrem Browser zu l\u00f6schen. Informationen \u00fcber die Konfiguration Ihrer Browsereinstellungen k\u00f6nnen Sie der Hilfefunktion Ihres jeweiligen Internetbrowsers entnehmen.<br><br>\n\nDer vorstehend beschriebene Einsatz des Tripadvisor-Plugins erfolgt ab dem 25.05.2018 aufgrund unserer berechtigten gesch\u00e4ftlichen Werbeinteressen und damit auf der Rechtsgrundlage von Artikel 6 Absatz 1 Buchstabe f) DSGVO.<br><br>\n\n\n<h3>16. Newsletter<\/h3>\nWir verwenden zum Versand unseres Newsletters den Dienstes MailChimp der Firma \u201eThe Rocket Science Group, LLC, 512 Means Street, Suite 404, Atlanta, GA 30318 (nachfolgend \u201cRocket\u201d genannt). Rocket ist nach den Vorgaben des Privacy-Shield-Abkommens der EU mit den USA zertifiziert und verpflichtet sich damit die EU-Datenschutzvorgaben einzuhalten.<br><br>\n\nNachfolgend informieren wir Sie \u00fcber den Bestell- und Versandprozess unseres Newsletters die K\u00fcndigung des Newsletters sowie die jeweiligen Datenverarbeitungsprozesse und die Rechtsgrundlage f\u00fcr den Einsatz unseres Newsletterdienstes:<br><br>\n\n\n<h3>a) Bestellung und Versand unseres Newsletters<\/h3>\nSofern Sie unseren Newsletter bestellen, m\u00fcssen die im Bestellprozess ersichtlichen personenbezogenen Daten eingeben. Ihre angegebenen Daten werden an Server von Rocket in den USA \u00fcbermittelt und von Rocket dort gespeichert. An andere Dritte werden die Daten, die Sie bei der Registrierung angegeben m\u00fcssen, nicht \u00fcbermittelt. Bei der erstmaligen Registrierung wird von Rocket aus rechtlichen Gr\u00fcnden eine Best\u00e4tigungsmail im Double-Opt-In-Verfahren an die in der Registrierung angegebene E-Mailadresse versendet, um eine Best\u00e4tigung des Empf\u00e4ngers zu erhalten, dass er der Inhaber der eingetragenen E-Mailadresse ist bzw. die Bestellung unseres Newsletters an seine E-Mailadresse autorisiert hat.<br><br>\n\nRocket verwendet Ihre Daten zum Versand und zur Auswertung unseres Newsletters in unserem Auftrag, wobei diese Analysen nur gruppenbezogen und nicht zur individuellen Auswertung verwendet werden. Rocket verwendet Ihre Daten auch zur Analyse und zur technischen Optimierung des Newsletterdienstes und bindet gegebenenfalls das Analysetool Google Analytics und den Google Tag Manager von der Firma Google LLC in die Newsletter ein. Die Einzelheiten zu Google-Analytics k\u00f6nnen Sie den vorstehenden Hinweisen zu diesem Dienst entnehmen.<br><br>\n\nDie Datenschutzbestimmungen von MailChimp k\u00f6nnen Sie unter folgendem Link einsehen:\n<a href=\"https:\/\/mailchimp.com\/legal\/privacy\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/mailchimp.com\/legal\/privacy\/<\/a><br><br>\n\n<h3>b) K\u00fcndigung des Newsletters:<\/h3>\nSie k\u00f6nnen den Newsletter jederzeit k\u00fcndigen, indem Sie die Abmeldefunktion nutzen, \u00fcber welche wir Sie in jedem Newsletter informieren. Durch die K\u00fcndigung des Newsletterdienstes wird auch die uns gegen\u00fcber erteilte Einwilligung f\u00fcr den Newsletterversand mit Wirkung f\u00fcr die Zukunft widerrufen. Die Rechtm\u00e4\u00dfigkeit der aufgrund der Einwilligung bis zum Widerruf erfolgten Datenverarbeitung wird durch den Widerruf nicht ber\u00fchrt.<br><br>\nNach K\u00fcndigung des Newsletterdienstes und Widerruf der Einwilligung werden Ihre personenbezogenen Daten nach Zweckfortfall routinem\u00e4\u00dfig gel\u00f6scht.<br><br>\nSofern einzelne Daten aufgrund von gesetzlichen Aufbewahrungsfristen aufbewahrt werden m\u00fcssen (z.B. steuer- und handelsrechtliche Aufbewahrungsvorschriften), tritt an die Stelle einer L\u00f6schung die Sperrung der Daten. Die aufzubewahrenden Daten d\u00fcrfen dann auf der Rechtsgrundlage des Artikels 6 Absatz 1 Buchstabe c) DSGVO ausschlie\u00dflich f\u00fcr die vorgenannten Zwecke verarbeitet werden.<br><br>\n<h3>c) Rechtsgrundlage f\u00fcr den Einsatz unseres Newsletters:<\/h3>\nDer vorstehend beschriebene Einsatz unseres Newsletters erfolgt ab dem 25.05.2018 auf der Rechtsgrundlage Ihrer Einwilligung und damit auf Art. 6 Abs. 1 Buchstabe a) DSGVO. Dar\u00fcber hinaus besteht f\u00fcr die Nutzung des Newsletterdienstes Mailchimp auch ein berechtigtes Interesse im Sinne des Art. 6 Abs. 1 Buchstabe f) DSGVO. Unser berechtigtes Interesse besteht darin, Ihnen einen nutzerfreundliches und sicheres Newsletter-Systems anzubieten, welches sowohl unseren gesch\u00e4ftlichen Interessen dient, als auch den Erwartungen der Nutzer entspricht.<br><br>\n\nStand der Datenschutzerkl\u00e4rung: 13.02.2023\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\/*! elementor &#8211; v3.10.2 &#8211; 29-01-2023 *\/ .elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]&gt;a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px} Datenschutzerkl\u00e4rung 1. Allgemeines Wir nehmen den Schutz Ihrer pers\u00f6nlichen Daten sehr ernst. Daten werden von uns gem\u00e4\u00df den geltenden gesetzlichen Datenschutzbestimmungen, ab dem 25.05.2018 insbesondere nach der europ\u00e4ischen Datenschutzgrundverordnung (im Folgenden: DSGVO genannt) sowie den landesspezifischen Datenschutzbestimmungen \u201everarbeitet\u201c. \u201eVerarbeitung\u201c ist jeder [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":11,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-34","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Datenschutz - Final Escape Flensburg<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.final-escape.com\/flensburg\/datenschutz\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Datenschutz - Final Escape Flensburg\" \/>\n<meta property=\"og:description\" content=\"\/*! elementor &#8211; v3.10.2 &#8211; 29-01-2023 *\/ .elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]&gt;a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px} Datenschutzerkl\u00e4rung 1. Allgemeines Wir nehmen den Schutz Ihrer pers\u00f6nlichen Daten sehr ernst. Daten werden von uns gem\u00e4\u00df den geltenden gesetzlichen Datenschutzbestimmungen, ab dem 25.05.2018 insbesondere nach der europ\u00e4ischen Datenschutzgrundverordnung (im Folgenden: DSGVO genannt) sowie den landesspezifischen Datenschutzbestimmungen \u201everarbeitet\u201c. \u201eVerarbeitung\u201c ist jeder [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.final-escape.com\/flensburg\/datenschutz\/\" \/>\n<meta property=\"og:site_name\" content=\"Final Escape Flensburg\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-13T09:11:13+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"27\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.final-escape.com\/flensburg\/datenschutz\/\",\"url\":\"https:\/\/www.final-escape.com\/flensburg\/datenschutz\/\",\"name\":\"Datenschutz - Final Escape Flensburg\",\"isPartOf\":{\"@id\":\"https:\/\/www.final-escape.com\/flensburg\/#website\"},\"datePublished\":\"2022-07-11T13:45:27+00:00\",\"dateModified\":\"2023-02-13T09:11:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.final-escape.com\/flensburg\/datenschutz\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.final-escape.com\/flensburg\/datenschutz\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.final-escape.com\/flensburg\/datenschutz\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.final-escape.com\/flensburg\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Datenschutz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.final-escape.com\/flensburg\/#website\",\"url\":\"https:\/\/www.final-escape.com\/flensburg\/\",\"name\":\"Final Escape Flensburg\",\"description\":\"Live Escape Games \/ Room Flensburg - Adventure Game \/ Rooms Flensburg\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.final-escape.com\/flensburg\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Datenschutz - Final Escape Flensburg","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.final-escape.com\/flensburg\/datenschutz\/","og_locale":"de_DE","og_type":"article","og_title":"Datenschutz - Final Escape Flensburg","og_description":"\/*! elementor &#8211; v3.10.2 &#8211; 29-01-2023 *\/ .elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]&gt;a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px} Datenschutzerkl\u00e4rung 1. Allgemeines Wir nehmen den Schutz Ihrer pers\u00f6nlichen Daten sehr ernst. Daten werden von uns gem\u00e4\u00df den geltenden gesetzlichen Datenschutzbestimmungen, ab dem 25.05.2018 insbesondere nach der europ\u00e4ischen Datenschutzgrundverordnung (im Folgenden: DSGVO genannt) sowie den landesspezifischen Datenschutzbestimmungen \u201everarbeitet\u201c. \u201eVerarbeitung\u201c ist jeder [&hellip;]","og_url":"https:\/\/www.final-escape.com\/flensburg\/datenschutz\/","og_site_name":"Final Escape Flensburg","article_modified_time":"2023-02-13T09:11:13+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"27\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.final-escape.com\/flensburg\/datenschutz\/","url":"https:\/\/www.final-escape.com\/flensburg\/datenschutz\/","name":"Datenschutz - Final Escape Flensburg","isPartOf":{"@id":"https:\/\/www.final-escape.com\/flensburg\/#website"},"datePublished":"2022-07-11T13:45:27+00:00","dateModified":"2023-02-13T09:11:13+00:00","breadcrumb":{"@id":"https:\/\/www.final-escape.com\/flensburg\/datenschutz\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.final-escape.com\/flensburg\/datenschutz\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.final-escape.com\/flensburg\/datenschutz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.final-escape.com\/flensburg\/en\/"},{"@type":"ListItem","position":2,"name":"Datenschutz"}]},{"@type":"WebSite","@id":"https:\/\/www.final-escape.com\/flensburg\/#website","url":"https:\/\/www.final-escape.com\/flensburg\/","name":"Final Escape Flensburg","description":"Live Escape Games \/ Room Flensburg - Adventure Game \/ Rooms Flensburg","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.final-escape.com\/flensburg\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.final-escape.com\/flensburg\/wp-json\/wp\/v2\/pages\/34"}],"collection":[{"href":"https:\/\/www.final-escape.com\/flensburg\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.final-escape.com\/flensburg\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.final-escape.com\/flensburg\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.final-escape.com\/flensburg\/wp-json\/wp\/v2\/comments?post=34"}],"version-history":[{"count":4,"href":"https:\/\/www.final-escape.com\/flensburg\/wp-json\/wp\/v2\/pages\/34\/revisions"}],"predecessor-version":[{"id":2119,"href":"https:\/\/www.final-escape.com\/flensburg\/wp-json\/wp\/v2\/pages\/34\/revisions\/2119"}],"wp:attachment":[{"href":"https:\/\/www.final-escape.com\/flensburg\/wp-json\/wp\/v2\/media?parent=34"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}