{"id":32,"date":"2022-07-11T15:45:27","date_gmt":"2022-07-11T13:45:27","guid":{"rendered":"https:\/\/www.final-escape.com\/kiel\/impressum\/"},"modified":"2025-08-04T17:45:35","modified_gmt":"2025-08-04T15:45:35","slug":"impressum","status":"publish","type":"page","link":"https:\/\/www.final-escape.com\/kiel\/impressum\/","title":{"rendered":"Impressum"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"32\" class=\"elementor elementor-32\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f6b4bc0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f6b4bc0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1a71aae\" data-id=\"1a71aae\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0cceb5c elementor-widget elementor-widget-heading\" data-id=\"0cceb5c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Impressum<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77b75ec elementor-widget elementor-widget-text-editor\" data-id=\"77b75ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Final Escape 2.2 GmbH<br \/>K\u00fcterstr. 14<br \/>24103 Kiel<\/p><p><strong>Vertretungsberechtigter Gesch\u00e4ftsf\u00fchrer:<\/strong>\u00a0Robert Schneider<\/p><p>Web: http:\/\/www.final-escape.com<br \/>E-Mail:\u00a0<a href=\"mailto:kiel@final-escape.de\">kiel@final-escape.de<\/a><br \/>Zentrale:\u00a0<a href=\"tel:043153037929\">0431 55602010<\/a><\/p><p>HR Zeichen: HRB 185 47 KI<br \/>Gerichtsstand: Amtsgericht Kiel<br \/>Tax ID: DE 304629367<\/p><p>Design &amp; Umsetzung:\u00a0<a href=\"https:\/\/www.minkenberg.de\/de\/\" target=\"_blank\" rel=\"noopener\">Minkenberg Medien GmbH<\/a><\/p><p>Einige Bilder und Icons auf unserer Homepage stammen von den Anbietern Font Awesome, Shutterstock und Dreamstime.<\/p><p><strong>HAFTUNGSHINWEIS:<\/strong><br \/>Trotz sorgf\u00e4ltiger inhaltlicher Kontrolle \u00fcbernehmen wir keine Haftung f\u00fcr die Inhalte externer Links. F\u00fcr den Inhalt der verlinkten Seiten sind ausschlie\u00dflich deren Betreiber verantwortlich. Wir m\u00f6chten ausdr\u00fccklich darauf hinweisen, dass wir uns von den Inhalten von dieser Internetpr\u00e4senz verlinkten Seiten distanzieren.<\/p><p>Wir weisen ausdr\u00fccklich darauf hin, dass wir keinerlei Einfluss auf die Inhalte der fremden Homepages haben. Sollten auf den fremden Seiten Verst\u00f6\u00dfe gegen die guten Sitten oder Gesetze enthalten sein, werden wir die Links zu diesen Seiten sofort nach Kenntnisnahme dieser Verst\u00f6\u00dfe aus unserer Internetpr\u00e4senz l\u00f6schen.<\/p><p><strong>COPYRIGHTHINWEIS:<\/strong><br \/>S\u00e4mtliche Inhalte sind urheberrechtlich gesch\u00fctzt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Impressum Final Escape 2.2 GmbHK\u00fcterstr. 1424103 Kiel Vertretungsberechtigter Gesch\u00e4ftsf\u00fchrer:\u00a0Robert Schneider Web: http:\/\/www.final-escape.comE-Mail:\u00a0kiel@final-escape.deZentrale:\u00a00431 55602010 HR Zeichen: HRB 185 47 KIGerichtsstand: Amtsgericht KielTax ID: DE 304629367 Design &amp; Umsetzung:\u00a0Minkenberg Medien GmbH Einige Bilder und Icons auf unserer Homepage stammen von den Anbietern Font Awesome, Shutterstock und Dreamstime. HAFTUNGSHINWEIS:Trotz sorgf\u00e4ltiger inhaltlicher Kontrolle \u00fcbernehmen wir keine Haftung f\u00fcr die [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":10,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-32","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Impressum - Final Escape Kiel<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.final-escape.com\/kiel\/impressum\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Impressum - Final Escape Kiel\" \/>\n<meta property=\"og:description\" content=\"Impressum Final Escape 2.2 GmbHK\u00fcterstr. 1424103 Kiel Vertretungsberechtigter Gesch\u00e4ftsf\u00fchrer:\u00a0Robert Schneider Web: http:\/\/www.final-escape.comE-Mail:\u00a0kiel@final-escape.deZentrale:\u00a00431 55602010 HR Zeichen: HRB 185 47 KIGerichtsstand: Amtsgericht KielTax ID: DE 304629367 Design &amp; Umsetzung:\u00a0Minkenberg Medien GmbH Einige Bilder und Icons auf unserer Homepage stammen von den Anbietern Font Awesome, Shutterstock und Dreamstime. HAFTUNGSHINWEIS:Trotz sorgf\u00e4ltiger inhaltlicher Kontrolle \u00fcbernehmen wir keine Haftung f\u00fcr die [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.final-escape.com\/kiel\/impressum\/\" \/>\n<meta property=\"og:site_name\" content=\"Final Escape Kiel\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-04T15:45:35+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.final-escape.com\\\/kiel\\\/impressum\\\/\",\"url\":\"https:\\\/\\\/www.final-escape.com\\\/kiel\\\/impressum\\\/\",\"name\":\"Impressum - Final Escape Kiel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.final-escape.com\\\/kiel\\\/#website\"},\"datePublished\":\"2022-07-11T13:45:27+00:00\",\"dateModified\":\"2025-08-04T15:45:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.final-escape.com\\\/kiel\\\/impressum\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.final-escape.com\\\/kiel\\\/impressum\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.final-escape.com\\\/kiel\\\/impressum\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.final-escape.com\\\/kiel\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Impressum\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.final-escape.com\\\/kiel\\\/#website\",\"url\":\"https:\\\/\\\/www.final-escape.com\\\/kiel\\\/\",\"name\":\"Final Escape Kiel\",\"description\":\"Live Escape Games Kiel\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.final-escape.com\\\/kiel\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Impressum - Final Escape Kiel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.final-escape.com\/kiel\/impressum\/","og_locale":"de_DE","og_type":"article","og_title":"Impressum - Final Escape Kiel","og_description":"Impressum Final Escape 2.2 GmbHK\u00fcterstr. 1424103 Kiel Vertretungsberechtigter Gesch\u00e4ftsf\u00fchrer:\u00a0Robert Schneider Web: http:\/\/www.final-escape.comE-Mail:\u00a0kiel@final-escape.deZentrale:\u00a00431 55602010 HR Zeichen: HRB 185 47 KIGerichtsstand: Amtsgericht KielTax ID: DE 304629367 Design &amp; Umsetzung:\u00a0Minkenberg Medien GmbH Einige Bilder und Icons auf unserer Homepage stammen von den Anbietern Font Awesome, Shutterstock und Dreamstime. HAFTUNGSHINWEIS:Trotz sorgf\u00e4ltiger inhaltlicher Kontrolle \u00fcbernehmen wir keine Haftung f\u00fcr die [&hellip;]","og_url":"https:\/\/www.final-escape.com\/kiel\/impressum\/","og_site_name":"Final Escape Kiel","article_modified_time":"2025-08-04T15:45:35+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.final-escape.com\/kiel\/impressum\/","url":"https:\/\/www.final-escape.com\/kiel\/impressum\/","name":"Impressum - Final Escape Kiel","isPartOf":{"@id":"https:\/\/www.final-escape.com\/kiel\/#website"},"datePublished":"2022-07-11T13:45:27+00:00","dateModified":"2025-08-04T15:45:35+00:00","breadcrumb":{"@id":"https:\/\/www.final-escape.com\/kiel\/impressum\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.final-escape.com\/kiel\/impressum\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.final-escape.com\/kiel\/impressum\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.final-escape.com\/kiel\/en\/"},{"@type":"ListItem","position":2,"name":"Impressum"}]},{"@type":"WebSite","@id":"https:\/\/www.final-escape.com\/kiel\/#website","url":"https:\/\/www.final-escape.com\/kiel\/","name":"Final Escape Kiel","description":"Live Escape Games Kiel","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.final-escape.com\/kiel\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.final-escape.com\/kiel\/wp-json\/wp\/v2\/pages\/32","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.final-escape.com\/kiel\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.final-escape.com\/kiel\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.final-escape.com\/kiel\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.final-escape.com\/kiel\/wp-json\/wp\/v2\/comments?post=32"}],"version-history":[{"count":10,"href":"https:\/\/www.final-escape.com\/kiel\/wp-json\/wp\/v2\/pages\/32\/revisions"}],"predecessor-version":[{"id":3813,"href":"https:\/\/www.final-escape.com\/kiel\/wp-json\/wp\/v2\/pages\/32\/revisions\/3813"}],"wp:attachment":[{"href":"https:\/\/www.final-escape.com\/kiel\/wp-json\/wp\/v2\/media?parent=32"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}